{"id":1339,"count":1,"description":"","link":"http:\/\/mirrorswindowsdoors.org\/wp\/tag\/keats\/","name":"Keats","slug":"keats","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Keats Archives ~<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/mirrorswindowsdoors.org\/wp\/tag\/keats\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Keats Archives ~\" \/>\n<meta property=\"og:url\" content=\"http:\/\/mirrorswindowsdoors.org\/wp\/tag\/keats\/\" \/>\n<meta property=\"og:image\" content=\"http:\/\/mirrorswindowsdoors.org\/wp\/wp-content\/uploads\/2014\/06\/MirrorsWindowsDoors_LOGO_01_22May2014_400pxWide_sharpened1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MarjorieMWD\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/mirrorswindowsdoors.org\/wp\/tag\/keats\/\",\"url\":\"http:\/\/mirrorswindowsdoors.org\/wp\/tag\/keats\/\",\"name\":\"Keats Archives ~\",\"isPartOf\":{\"@id\":\"http:\/\/mirrorswindowsdoors.org\/wp\/#website\"},\"breadcrumb\":{\"@id\":\"http:\/\/mirrorswindowsdoors.org\/wp\/tag\/keats\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/mirrorswindowsdoors.org\/wp\/tag\/keats\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/mirrorswindowsdoors.org\/wp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Keats\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/mirrorswindowsdoors.org\/wp\/#website\",\"url\":\"http:\/\/mirrorswindowsdoors.org\/wp\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\/\/mirrorswindowsdoors.org\/wp\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/mirrorswindowsdoors.org\/wp\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/mirrorswindowsdoors.org\/wp\/#organization\",\"name\":\"Mirrors Windows Doors\",\"url\":\"http:\/\/mirrorswindowsdoors.org\/wp\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"http:\/\/mirrorswindowsdoors.org\/wp\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/mirrorswindowsdoors.org\/wp\/wp-content\/uploads\/2014\/06\/Slide_logo.jpg\",\"contentUrl\":\"http:\/\/mirrorswindowsdoors.org\/wp\/wp-content\/uploads\/2014\/06\/Slide_logo.jpg\",\"width\":1150,\"height\":400,\"caption\":\"Mirrors Windows Doors\"},\"image\":{\"@id\":\"http:\/\/mirrorswindowsdoors.org\/wp\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/mirrorswindowsdoors\",\"https:\/\/twitter.com\/MarjorieMWD\",\"https:\/\/uk.pinterest.com\/marjorie_mwd\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Keats Archives ~","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/mirrorswindowsdoors.org\/wp\/tag\/keats\/","og_locale":"en_GB","og_type":"article","og_title":"Keats Archives ~","og_url":"http:\/\/mirrorswindowsdoors.org\/wp\/tag\/keats\/","og_image":[{"width":400,"height":183,"url":"http:\/\/mirrorswindowsdoors.org\/wp\/wp-content\/uploads\/2014\/06\/MirrorsWindowsDoors_LOGO_01_22May2014_400pxWide_sharpened1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MarjorieMWD","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/mirrorswindowsdoors.org\/wp\/tag\/keats\/","url":"http:\/\/mirrorswindowsdoors.org\/wp\/tag\/keats\/","name":"Keats Archives ~","isPartOf":{"@id":"http:\/\/mirrorswindowsdoors.org\/wp\/#website"},"breadcrumb":{"@id":"http:\/\/mirrorswindowsdoors.org\/wp\/tag\/keats\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"http:\/\/mirrorswindowsdoors.org\/wp\/tag\/keats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/mirrorswindowsdoors.org\/wp\/"},{"@type":"ListItem","position":2,"name":"Keats"}]},{"@type":"WebSite","@id":"http:\/\/mirrorswindowsdoors.org\/wp\/#website","url":"http:\/\/mirrorswindowsdoors.org\/wp\/","name":"","description":"","publisher":{"@id":"http:\/\/mirrorswindowsdoors.org\/wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/mirrorswindowsdoors.org\/wp\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"http:\/\/mirrorswindowsdoors.org\/wp\/#organization","name":"Mirrors Windows Doors","url":"http:\/\/mirrorswindowsdoors.org\/wp\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"http:\/\/mirrorswindowsdoors.org\/wp\/#\/schema\/logo\/image\/","url":"http:\/\/mirrorswindowsdoors.org\/wp\/wp-content\/uploads\/2014\/06\/Slide_logo.jpg","contentUrl":"http:\/\/mirrorswindowsdoors.org\/wp\/wp-content\/uploads\/2014\/06\/Slide_logo.jpg","width":1150,"height":400,"caption":"Mirrors Windows Doors"},"image":{"@id":"http:\/\/mirrorswindowsdoors.org\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mirrorswindowsdoors","https:\/\/twitter.com\/MarjorieMWD","https:\/\/uk.pinterest.com\/marjorie_mwd\/"]}]}},"_links":{"self":[{"href":"http:\/\/mirrorswindowsdoors.org\/wp\/wp-json\/wp\/v2\/tags\/1339"}],"collection":[{"href":"http:\/\/mirrorswindowsdoors.org\/wp\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/mirrorswindowsdoors.org\/wp\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/mirrorswindowsdoors.org\/wp\/wp-json\/wp\/v2\/posts?tags=1339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}